{"id":657,"date":"2024-11-21T12:34:19","date_gmt":"2024-11-21T10:34:19","guid":{"rendered":"https:\/\/biomarato.org\/catalunya\/2024\/11\/21\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/"},"modified":"2025-02-28T18:42:20","modified_gmt":"2025-02-28T16:42:20","slug":"la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar","status":"publish","type":"post","link":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/","title":{"rendered":"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l&#8217;Ametlla de Mar"},"content":{"rendered":"<p>El pasado s\u00e1bado, 9 de noviembre, el Centro de Interpretaci\u00f3n de la Pesca (CIP) de la Ametlla de Mar fue el escenario de la Fiesta del Voluntariado, un encuentro que sirvi\u00f3 para celebrar la clausura de la BioMARat\u00f3n 2024 y reconocer la labor de los participantes en este proyecto de ciencia ciudadana.<\/p>\n<p>El evento, impulsado por el Instituto de Ciencias del Mar (ICM-CSIC) y apoyado por entidades como la Federaci\u00f3n Catalana de Actividades Subacu\u00e1ticas (FECDAS), la Asociaci\u00f3n Oce\u00e1nicos, An\u00e9lidas \u2013 Servicios Ambientales Marinos y Plancton Diving, reuni\u00f3 aficionados y expertos en el campo de la biodiversidad marina.<\/p>\n<p>La jornada comenz\u00f3 con diversas actividades opcionales a primera hora, entre las que se encontraba una salida colectiva de buceo y esn\u00f3rquel, organizada en la playa en colaboraci\u00f3n con Plancton Diving.<\/p>\n<p>El acto central se inici\u00f3 con la bienvenida de la alcaldesa de la Ametlla de Mar, Eva del Amo, y Jaume Piera, investigador del ICM-CSIC y responsable de la BioMARat\u00f3, quienes agradecieron el compromiso de la comunidad y remarcaron la importancia de la ciencia ciudadana para la conservaci\u00f3n de nuestro entorno. Durante la celebraci\u00f3n, se estren\u00f3 un nuevo v\u00eddeo promocional, se compartieron los resultados de la edici\u00f3n 2024 y se entregaron los premios a los participantes ganadores, con galardones como salidas de buceo guiadas y cursos de biolog\u00eda marina, gracias a la gentileza de las entidades movilizadoras y de Cressi. Durante el acto tambi\u00e9n se disput\u00f3 un juego de adivinar especias utilizando los m\u00f3viles que, seg\u00fan el p\u00fablico, fue una de las actividades m\u00e1s divertidas del acto.<\/p>\n<p>El punto final lo puso un agradable picoteo, donde los asistentes pudieron compartir experiencias y proyectos de futuro. La Fiesta del Voluntariado se consolid\u00f3 como un espacio de agradecimiento y reconocimiento para todas las personas que han contribuido a la BioMARat\u00f3 2024, un proyecto que no s\u00f3lo promueve el conocimiento y la conservaci\u00f3n de la biodiversidad marina, sino que tambi\u00e9n refuerza los lazos de la comunidad en la lucha por preservar nuestro medio marino.<\/p>\n<h4><strong>Premis BioMARat\u00f3 2024<\/strong><\/h4>\n<h5><strong>Categoria general:<\/strong><\/h5>\n<ul>\n<li>1r premi: Val de 200\u20ac per gastar a la botiga Cressi \u2013\u00a0<strong>Edu Alca\u00f1iz<\/strong><\/li>\n<li>2n premi: Val de 100\u20ac per gastar a la botiga Cressi \u2013\u00a0<strong>Jose Manuel Moral<\/strong><\/li>\n<li>3r premi: Val de 50\u20ac per gastar a la botiga Cressi \u2013\u00a0<strong>Miquel Figueras<\/strong><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-850\" src=\"https:\/\/biomarato.org\/wp-content\/uploads\/2024\/11\/2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1702\" \/><\/p>\n<h5><strong>Prov\u00edncia de Barcelona:<\/strong><\/h5>\n<ul>\n<li>1r premi: Sortida de busseig per observar gorg\u00f2nies a Barcelona amb FECDAS \u2013\u00a0<strong>Nuria Gonzalez Carretero<\/strong><\/li>\n<li>2n premi: 2 places de bateig de submarinisme amb taller de biologia marina incl\u00f2s, amb An\u00e8l\u00b7lides i Free and divers \u2013\u00a0<strong>Nuria Gonzalez Cubells<\/strong><\/li>\n<li>3r premi: Joc de BCN PEIXOS + Guia Participativa del Barcelon\u00e8s d\u2019An\u00e8l\u00b7lides \u2013\u00a0<strong>Virginia Abenia<\/strong><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-853\" src=\"https:\/\/biomarato.org\/wp-content\/uploads\/2024\/11\/Sense-titol-580-x-330-px-4-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1702\" \/><\/p>\n<h5><strong>Prov\u00edncia de Tarragona:<\/strong><\/h5>\n<ul>\n<li>1r premi: Curs de formaci\u00f3 de mostreig de faner\u00f2games (Posidonia oceanica i Cymodocea nodosa) amb immersi\u00f3 cient\u00edfica dins del PROJECTE END\u00c8MICS, gentilesa de l\u2019Associaci\u00f3 Oce\u00e1nicos \/ Curs \u201cIntroducci\u00f3 a la Biologia Marina\u201d amb Pl\u00e0ncton Diving \u2013\u00a0<strong>Guillem Mayor<\/strong><\/li>\n<li>2n premi: Immersi\u00f3 guiada des de barca amb l\u2019Associaci\u00f3 Oce\u00e1nicos \/ 2 places de bateig de submarinisme amb Pl\u00e0ncton Diving \u2013\u00a0<strong>Anna Canela<\/strong><\/li>\n<li>3r premi: Immersi\u00f3 guiada des de la platja amb l\u2019Associaci\u00f3 Oce\u00e1nicos\/ 2 places de snorkel guiat amb Pl\u00e0ncton Diving \u2013\u00a0<strong>Eva Ram\u00edrez<\/strong><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-856\" src=\"https:\/\/biomarato.org\/wp-content\/uploads\/2024\/11\/3-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1702\" \/><\/p>\n<h5><strong>Prov\u00edncia de Girona:<\/strong><\/h5>\n<ul>\n<li>1r premi: Sortida d\u2019immersi\u00f3 a les illes Medes amb el projecte ANERIS (FECDAS) \u2013\u00a0<strong>Miquel Pontes<\/strong><\/li>\n<li>2n premi: Sortida d\u2019immersi\u00f3 a Platja d\u2019Aro amb el projecte ANERIS (FECDAS) \u2013\u00a0<strong>Adri\u00e0 Compte<\/strong><\/li>\n<li>3r premi: Exemplar del llibre \u201cGuia pr\u00e0ctica per fotografiar nudibranquis del litoral espanyol\u201d de Xavier Salvador (ICM-CSIC) \u2013\u00a0<strong>Manel Ortega<\/strong><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-859\" src=\"https:\/\/biomarato.org\/wp-content\/uploads\/2024\/11\/5-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1702\" \/><\/p>\n<p><strong>Premis aleatoris:<\/strong><\/p>\n<p>5 places al curs online de fotografia subaqu\u00e0tica amb Xavier Salvador, gentilesa de l\u2019equip ICM:\u00a0<strong>David Marco, Gonzalo Zafra, Jaume Alaball, Albert Vim i Conxi<\/strong>.<\/p>\n<p>Curs de busseig cient\u00edfic amb FECDAS \u2013\u00a0<strong>Enric Badosa<\/strong><\/p>\n<p>7 places de snorkel guiat amb l\u2019equip ICM a l\u2019abril, per participar en el BioDiverCiutat \u2013 City Nature Challenge:\u00a0<strong>Estrella Rib\u00f3, Nerea Vieitez, Joan Div\u00ed, Pau Pag\u00e8s, Marta Nadal, David Aland\u00ed, Irene Bernabeu.<\/strong><\/p>\n<p><a href=\"https:\/\/saco.csic.es\/s\/5zMKaWrZnwEGSN4\"><strong>VEURE LA GALERIA COMPLETA DE FOTOS<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado, 9 de noviembre, el Centro de Interpretaci\u00f3n de la Pesca (CIP) de la Ametlla de Mar fue el escenario de la Fiesta del Voluntariado, un encuentro que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l&#039;Ametlla de Mar - Catalunya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l&#039;Ametlla de Mar - Catalunya\" \/>\n<meta property=\"og:description\" content=\"El pasado s\u00e1bado, 9 de noviembre, el Centro de Interpretaci\u00f3n de la Pesca (CIP) de la Ametlla de Mar fue el escenario de la Fiesta del Voluntariado, un encuentro que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/\" \/>\n<meta property=\"og:site_name\" content=\"Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-21T10:34:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-28T16:42:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biomarato.org\/catalunya\/wp-content\/uploads\/sites\/3\/2025\/01\/Sense-titol-580-x-330-px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/#\\\/schema\\\/person\\\/ff7b95cd44e19c2af4269c72bd631951\"},\"headline\":\"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l&#8217;Ametlla de Mar\",\"datePublished\":\"2024-11-21T10:34:19+00:00\",\"dateModified\":\"2025-02-28T16:42:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/\"},\"wordCount\":693,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Sense-titol-580-x-330-px.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/\",\"url\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/\",\"name\":\"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l'Ametlla de Mar - Catalunya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Sense-titol-580-x-330-px.jpg\",\"datePublished\":\"2024-11-21T10:34:19+00:00\",\"dateModified\":\"2025-02-28T16:42:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/#\\\/schema\\\/person\\\/ff7b95cd44e19c2af4269c72bd631951\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Sense-titol-580-x-330-px.jpg\",\"contentUrl\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Sense-titol-580-x-330-px.jpg\",\"width\":580,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l&#8217;Ametlla de Mar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/\",\"name\":\"Catalunya\",\"description\":\"Una iniciativa per descobrir la biodiversitat marina amb la ci\u00e8ncia ciutadana\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biomarato.org\\\/catalunya\\\/es\\\/#\\\/schema\\\/person\\\/ff7b95cd44e19c2af4269c72bd631951\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9d1bfedf501cbd8ae27b11de9986604bf4cdcea73b507457dfd4ff5dc770b75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9d1bfedf501cbd8ae27b11de9986604bf4cdcea73b507457dfd4ff5dc770b75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a9d1bfedf501cbd8ae27b11de9986604bf4cdcea73b507457dfd4ff5dc770b75?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/biomarato.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l'Ametlla de Mar - Catalunya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/","og_locale":"es_ES","og_type":"article","og_title":"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l'Ametlla de Mar - Catalunya","og_description":"El pasado s\u00e1bado, 9 de noviembre, el Centro de Interpretaci\u00f3n de la Pesca (CIP) de la Ametlla de Mar fue el escenario de la Fiesta del Voluntariado, un encuentro que [&hellip;]","og_url":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/","og_site_name":"Catalunya","article_published_time":"2024-11-21T10:34:19+00:00","article_modified_time":"2025-02-28T16:42:20+00:00","og_image":[{"width":580,"height":330,"url":"https:\/\/biomarato.org\/catalunya\/wp-content\/uploads\/sites\/3\/2025\/01\/Sense-titol-580-x-330-px.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#article","isPartOf":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/"},"author":{"name":"admin","@id":"https:\/\/biomarato.org\/catalunya\/es\/#\/schema\/person\/ff7b95cd44e19c2af4269c72bd631951"},"headline":"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l&#8217;Ametlla de Mar","datePublished":"2024-11-21T10:34:19+00:00","dateModified":"2025-02-28T16:42:20+00:00","mainEntityOfPage":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/"},"wordCount":693,"commentCount":0,"image":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#primaryimage"},"thumbnailUrl":"https:\/\/biomarato.org\/catalunya\/wp-content\/uploads\/sites\/3\/2025\/01\/Sense-titol-580-x-330-px.jpg","articleSection":["Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/","url":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/","name":"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l'Ametlla de Mar - Catalunya","isPartOf":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#primaryimage"},"image":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#primaryimage"},"thumbnailUrl":"https:\/\/biomarato.org\/catalunya\/wp-content\/uploads\/sites\/3\/2025\/01\/Sense-titol-580-x-330-px.jpg","datePublished":"2024-11-21T10:34:19+00:00","dateModified":"2025-02-28T16:42:20+00:00","author":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/#\/schema\/person\/ff7b95cd44e19c2af4269c72bd631951"},"breadcrumb":{"@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#primaryimage","url":"https:\/\/biomarato.org\/catalunya\/wp-content\/uploads\/sites\/3\/2025\/01\/Sense-titol-580-x-330-px.jpg","contentUrl":"https:\/\/biomarato.org\/catalunya\/wp-content\/uploads\/sites\/3\/2025\/01\/Sense-titol-580-x-330-px.jpg","width":580,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/biomarato.org\/catalunya\/es\/la-festa-del-voluntariat-tanca-amb-exit-la-biomarato-2024-a-lametlla-de-mar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/biomarato.org\/catalunya\/es\/home\/"},{"@type":"ListItem","position":2,"name":"La Fiesta del Voluntariado cierra con \u00e9xito la BioMARat\u00f3 2024 en l&#8217;Ametlla de Mar"}]},{"@type":"WebSite","@id":"https:\/\/biomarato.org\/catalunya\/es\/#website","url":"https:\/\/biomarato.org\/catalunya\/es\/","name":"Catalunya","description":"Una iniciativa per descobrir la biodiversitat marina amb la ci\u00e8ncia ciutadana","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biomarato.org\/catalunya\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/biomarato.org\/catalunya\/es\/#\/schema\/person\/ff7b95cd44e19c2af4269c72bd631951","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a9d1bfedf501cbd8ae27b11de9986604bf4cdcea73b507457dfd4ff5dc770b75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a9d1bfedf501cbd8ae27b11de9986604bf4cdcea73b507457dfd4ff5dc770b75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a9d1bfedf501cbd8ae27b11de9986604bf4cdcea73b507457dfd4ff5dc770b75?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/biomarato.org"]}]}},"_links":{"self":[{"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/posts\/657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/comments?post=657"}],"version-history":[{"count":2,"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/posts\/657\/revisions"}],"predecessor-version":[{"id":659,"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/posts\/657\/revisions\/659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/media\/482"}],"wp:attachment":[{"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/media?parent=657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/categories?post=657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biomarato.org\/catalunya\/es\/wp-json\/wp\/v2\/tags?post=657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}